{"id":8551,"date":"2018-12-18T10:26:44","date_gmt":"2018-12-18T09:26:44","guid":{"rendered":"http:\/\/www.chiesedisicilia.org\/chiesedisicilia\/?p=8551"},"modified":"2018-12-18T10:26:45","modified_gmt":"2018-02-21T10:26:45","slug":"la-tutela-dei-soggetti-deboli-tra-famiglia-e-societa-un-ciclo-di-quattro-seminari-della-cattedra-di-dialogo-tra-le-culture","status":"publish","type":"post","link":"https:\/\/www.chiesedisicilia.org\/2018\/12\/18\/la-tutela-dei-soggetti-deboli-tra-famiglia-e-societa-un-ciclo-di-quattro-seminari-della-cattedra-di-dialogo-tra-le-culture\/","title":{"rendered":"\u201cLA TUTELA DEI SOGGETTI DEBOLI TRA FAMIGLIA E SOCIET\u00c0\u201d: UN CICLO DI QUATTRO SEMINARI DELLA CATTEDRA DI DIALOGO TRA LE CULTURE"},"content":{"rendered":"<p>Si partir\u00e0 con l\u2019intervento di Giuseppe Di Mauro, componente del direttivo della Cattedra e vicedirettore dell\u2019Ufficio per la cultura della diocesi di Ragusa, che proporr\u00e0 una relazione di taglio antropologico dedicata ad un ripensamento dei concetti di \u201cfragilit\u00e0\u201d e \u201cpreziosit\u00e0\u201d all\u2019interno dell\u2019etica applicata alla vita.<\/p>\n<p>Seguendo un\u2019ormai consolidata metodologia interdisciplinare, seguir\u00e0 la relazione di Rosario Giurato, specialista in oncologia, medicina interna, medicina palliativa e terapia del dolore, sul tema del prendersi cura della persona morente nella sua globalit\u00e0, alleviandone le sofferenze senza artificiosi tecnicismi, nel pieno rispetto della sua dignit\u00e0 e volont\u00e0.<\/p>\n<p>Ad affrontare l&#8217;ambito giuridico sar\u00e0 l\u2019avvocato Cristina Di Paola, dell&#8217;Ordine forense di Ragusa, che si soffermer\u00e0 sulla \u201cposizione dei soggetti terzi e la punibilit\u00e0 della condotta di aiuto al suicidio\u201d. Concluder\u00e0 i lavori l\u2019avvocato Maria Arezzo, anche lei dell\u2019Ordine forense di Ragusa, che parler\u00e0 de \u201c<em>Il testamento biologico: il rifiuto di trattamento medico e le scelte di fine vita. Il lungo, non concluso, percorso dal contrasto tra la tesi disponibilista e quella indisponibilista del diritto alla vita sino alla Legge 219\/17<\/em>\u201d.<\/p>\n<p>A moderare i lavori il giornalista Antonello Lauretta.<\/p>\n<p>I successivi seminari, a cadenza mensile, saranno dedicati ai soggetti fragili nell\u2019ambito dell\u2019immigrazione, del lavoro e del mondo femminile nel contesto multiculturale. La conclusione a maggio con \u201c<em>La donna nella tragedia<\/em>\u201d: in programma interventi trasversali che spazieranno tra letteratura, filosofia e diritto, fino ad interpretazioni dal vivo di alcuni stralci di tragedie greche rappresentate in contemporanea a Siracusa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sar\u00e0 la tavola rotonda dedicata alle \u201cQuestioni di bioetica di fine vita\u201d ad inaugurare, a Ragusa, i quattro seminari che la Cattedra di dialogo tra le culture organizza in collaborazione con l\u2019Ordine forense cittadino. Ad aprire il ciclo, promosso con l\u2019obiettivo di invitare la cittadinanza a riflettere su \u201cLa tutela dei soggetti deboli tra famiglia e societ\u00e0\u201d, l\u2019incontro in programma marted\u00ec 18 dicembre, alle ore 16, nel salone della parrocchia Preziosissimo Sangue, a Ragusa. <\/p>\n","protected":false},"author":4,"featured_media":8552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[183,181,126,182],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/8551"}],"collection":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/comments?post=8551"}],"version-history":[{"count":2,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/8551\/revisions"}],"predecessor-version":[{"id":8554,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/8551\/revisions\/8554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/media\/8552"}],"wp:attachment":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/media?parent=8551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/categories?post=8551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/tags?post=8551"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/news-destination?post=8551"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/news-source?post=8551"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/is_homepage?post=8551"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/ta_other?post=8551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}