{"id":3364,"date":"2013-03-01T10:47:00","date_gmt":"2013-03-01T09:47:00","guid":{"rendered":"http:\/\/wptestsite.tecnavia.com\/chiesedisicilia_clientsite\/news\/2013\/03\/01\/palermo-ecumenismo-giornata-mondiale-di-preghiera-per-le-donne\/"},"modified":"2018-11-12T07:58:13","modified_gmt":"2018-01-16T07:58:13","slug":"palermo-ecumenismo-giornata-mondiale-di-preghiera-per-le-donne","status":"publish","type":"post","link":"https:\/\/www.chiesedisicilia.org\/2013\/03\/01\/palermo-ecumenismo-giornata-mondiale-di-preghiera-per-le-donne\/","title":{"rendered":"PALERMO. ECUMENISMO: GIORNATA MONDIALE DI PREGHIERA PER LE DONNE"},"content":{"rendered":"<div><span style=\"font-family: 'Times New Roman','serif'; font-size: 12pt; mso-fareast-font-family: Calibri; mso-fareast-theme-font: minor-latin; mso-fareast-language: IT; mso-ansi-language: IT; mso-bidi-language: AR-SA\">Nell\u2019ambito degli incontri ecumenici 2012\/2013, a cura dell\u2019Ufficio Pastorale per l\u2019Ecumenismo e il Dialogo Interreligioso della Diocesi di Palermo, diretto da don Piero Magro, oggi, venerd\u00ec 1 marzo, presso la Casa San Francesco in via della Infermeria ai Cappuccini, a Palermo, si svolger\u00e0 \u201cLa preghiera per la Donna\u201d. Dopo l\u2019accoglienza e i saluti, il programma prevede alle ore 20.30 la preghiera, alle ore 21.30 una piccola agape.<br \/>Promuovono l\u2019incontro: Chiesa Anglicana, Chiesa Avventista del 7\u00b0 Giorno, Chiesa Cattolica, Chiesa Evangelica della Riconciliazione, Chiesa Evangelica Luterana, Chiese Valdesi e Chiesa Metodista, Parrocchie Ortodosse di S. Marco di Efeso e San Caralampo, Vicariato per la Sicilia dell\u2019Arcidiocesi Ortodossa d\u2019Italia e Malta. [01]<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/3364"}],"collection":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/comments?post=3364"}],"version-history":[{"count":1,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/3364\/revisions"}],"predecessor-version":[{"id":21840,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/3364\/revisions\/21840"}],"wp:attachment":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/media?parent=3364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/categories?post=3364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/tags?post=3364"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/news-destination?post=3364"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/news-source?post=3364"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/is_homepage?post=3364"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/ta_other?post=3364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}