{"id":3360,"date":"2013-02-22T11:59:00","date_gmt":"2013-02-22T10:59:00","guid":{"rendered":"http:\/\/wptestsite.tecnavia.com\/chiesedisicilia_clientsite\/news\/2013\/02\/22\/palermo-fede-e-legalita-marcia-contro-la-mafia\/"},"modified":"2018-11-12T07:58:13","modified_gmt":"2018-01-16T07:58:13","slug":"palermo-fede-e-legalita-marcia-contro-la-mafia","status":"publish","type":"post","link":"https:\/\/www.chiesedisicilia.org\/2013\/02\/22\/palermo-fede-e-legalita-marcia-contro-la-mafia\/","title":{"rendered":"PALERMO. FEDE E LEGALITA\u2019: MARCIA CONTRO LA MAFIA"},"content":{"rendered":"<div>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span style=\"font-family: 'Times New Roman','serif'; font-size: 12pt\">\u201cVogliamo che lo Stato dia pi\u00f9 sicurezza ai cittadini, i quali si sentono lasciati in balia di se stessi, di fronte alla spavalderia ed alla sfida del potere mafioso. Vogliamo che partiti, Parlamento e Governo si decidano finalmente ad uscire dall&#8217;inerzia, vogliamo che la classe politica ed amministrativa sia limpida nell\u2019amministrazione della cosa pubblica e non si assista allo scandalo di vedere uomini politici affollare i funerali di noti mafiosi\u201d. Scrivevano cos\u00ec alcuni giovani presbiteri trent\u2019anni orsono in occasione degli omicidi di mafia perpetrati nel triangolo della morte Bagheria, Casteldaccia ed Altavilla Milicia.<br \/>Tale presa di coscienza sfoci\u00f2 con un documento redatto dal Coordinamento interparrocchiale che fu letto in tutte le chiese il 15 agosto del 1982. Un documento che separava nettamente gli uomini che portano la morte dal Cristianesimo. Il 26 febbraio del 1983 nelle strade del \u201cTriangolo della morte\u201d si snod\u00f2 una grande marcia contro la mafia che la Chiesa e la societ\u00e0 civile organizzarono camminando a testa alta. Studenti, fedeli e semplici cittadini, con coraggio si impegnarono pubblicamente contro la mafia. A trent\u2019anni da quella grande manifestazione, la marcia sar\u00e0 ripetuta oggi,\u00a0marted\u00ec 26 febbraio, e partir\u00e0 ancora una volta da Bagheria per raggiungere la piazza di Casteldaccia. Come fece allora il cardinale Salvatore Pappalardo, anche in questa circostanza il cardinale Paolo Romeo ha dato la sua adesione all\u2019iniziativa. [01]<o:p><\/o:p><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/3360"}],"collection":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/comments?post=3360"}],"version-history":[{"count":1,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/3360\/revisions"}],"predecessor-version":[{"id":21834,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/3360\/revisions\/21834"}],"wp:attachment":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/media?parent=3360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/categories?post=3360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/tags?post=3360"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/news-destination?post=3360"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/news-source?post=3360"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/is_homepage?post=3360"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/ta_other?post=3360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}