{"id":3028,"date":"2013-04-22T13:24:00","date_gmt":"2013-04-22T11:24:00","guid":{"rendered":"http:\/\/wptestsite.tecnavia.com\/chiesedisicilia_clientsite\/news\/2013\/04\/22\/noto-50-anniversario-episcopale-di-mons-salvatore-nicolosi\/"},"modified":"2018-11-12T07:58:07","modified_gmt":"2018-01-16T07:58:07","slug":"noto-50-anniversario-episcopale-di-mons-salvatore-nicolosi","status":"publish","type":"post","link":"https:\/\/www.chiesedisicilia.org\/2013\/04\/22\/noto-50-anniversario-episcopale-di-mons-salvatore-nicolosi\/","title":{"rendered":"NOTO. 50\u00b0 ANNIVERSARIO EPISCOPALE DI MONS. SALVATORE NICOLOSI"},"content":{"rendered":"<p class=\"MsoNormal\"><span style=\"font-family: 'Times New Roman';\"><span style=\"font-size: 12pt;\">Oggi, luned\u00ec\u00a0 22 Aprile, la Diocesi di Noto si stringe attorno al Vescovo emerito, mons. Salvatore Nicolosi, in occasione del 50\u00b0 anniversario della sua ordinazione episcopale. \u201cMons. Nicolosi \u00e8 uno dei pochi Padri Conciliari ancora viventi \u2013 si legge in una nota stampa della Diocesi &#8211; che ha indirizzato in maniera esemplare la Chiesa di Noto nel cammino ecclesiale con uno stile squisitamente sinodale, nei suoi 28 anni di episcopato\u00a0 trascorsi alla guida della Diocesi netina\u201d. La ricorrenza sar\u00e0 scandita da una solenne celebrazione eucaristica che si svolger\u00e0 nella Basilica Cattedrale alle ore 18:30, presieduta dal Card. Romeo e vedr\u00e0 la partecipazione di tutti i Vescovi di Sicilia, convenuti a Noto per la Conferenza Episcopale Siciliana, che si terr\u00e0 da oggi a mercoled\u00ec 24 Aprile.<\/span><\/span><\/p>\n<p class=\"MsoNormal\"><span style=\"font-family: 'Times New Roman';\"><span style=\"font-size: 12pt;\">Nella stessa celebrazione verr\u00e0 ricordato il 25\u00b0 anniversario di Gemellaggio tra la Diocesi di Noto e quella di Butembo-Beni (Repubblica Democratica del Congo), rappresentata dal Vescovo mons. Sikuli<\/span><span style=\"font-size: 12pt;\">\u00a0 <\/span><span style=\"font-size: 12pt;\">Melchisedek e da una delegazione che lo accompagna.<\/span><\/span><\/p>\n<p class=\"MsoNormal\"><span style=\"font-family: 'Times New Roman';\"><span style=\"font-size: 12pt;\">La Santa Messa sar\u00e0 preceduta, alle ore 17, da un Convegno diocesano che si svolger\u00e0 nell\u2019Aula Magna del Seminario Vescovile\u00a0 sul tema: \u201c25 anni del Gemellaggio\u201d. Al Convegno interverranno don Michele Fidone, direttore diocesano dell\u2019Ufficio Missionario, don Salvatore Cerruto che racconter\u00e0\u00a0 i suoi tre anni di vita vissuti a Butembo-Beni, Gianni Novello che spiegher\u00e0 i frutti che ha prodotto il dono del gemellaggio in questi 25 anni e concluder\u00e0 don Jean Bonane di Butembo-Beni che parler\u00e0 del\u00a0 gemellaggio tra le Diocesi di Noto e la sua Chiesa d\u2019origine alla luce del Vaticano II, mettendo in risalto la comprensione e le prospettive missiologiche. [01]<\/span><\/span><span style=\"font-size:12.0pt;font-family:\"Times New Roman\",\"serif\"\"><o:p><\/o:p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/3028"}],"collection":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/comments?post=3028"}],"version-history":[{"count":1,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/3028\/revisions"}],"predecessor-version":[{"id":21504,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/posts\/3028\/revisions\/21504"}],"wp:attachment":[{"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/media?parent=3028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/categories?post=3028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/tags?post=3028"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/news-destination?post=3028"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/news-source?post=3028"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/is_homepage?post=3028"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.chiesedisicilia.org\/chiesedisicilia\/news\/wp-json\/wp\/v2\/ta_other?post=3028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}